{"id":60993,"date":"2024-07-20T11:05:28","date_gmt":"2024-07-20T09:05:28","guid":{"rendered":"https:\/\/angebote.immobilienmoser.de\/immobilien\/vermietet-klein-gemuetlich-neu-renovierte-2-zimmerwohnung-mitten-in-bornheim-berger-str\/"},"modified":"2024-07-21T19:21:59","modified_gmt":"2024-07-21T17:21:59","slug":"vermietet-klein-gemuetlich-neu-renovierte-2-zimmerwohnung-mitten-in-bornheim-berger-str","status":"publish","type":"property","link":"https:\/\/angebote.immobilienmoser.de\/en\/immobilien\/vermietet-klein-gemuetlich-neu-renovierte-2-zimmerwohnung-mitten-in-bornheim-berger-str\/","title":{"rendered":"VERMIETET! Klein! Gem\u00fctlich! Neu renovierte 2 Zimmerwohnung &#8211; mitten in Bornheim Berger Str."},"content":{"rendered":"<div class=\"block-title-wrap\">\n<h2>Property description<\/h2>\n<\/div>\n<p>In diesem zentral gelegenen Altbau aus der Jahrhundertwende direkt auf der Berger Stra\u00dfe wurde  im 1. OG  diese richtig gem\u00fctliche kleine 2-Zimmerwohnung grade fertig renoviert.  <\/p>\n<p>Ideal f\u00fcr eine Single-Nutzung, max. jedoch 2 Personen und aufgrund des Grundrisses (hintereinander liegende Zimmer) f\u00fcr eine WG eher nicht m\u00f6glich.<\/p>\n<div class=\"block-title-wrap\">\n<h2>equipment<\/h2>\n<\/div>\n<p>Der Boden jetzt neu mit schickem Vynil ausgestattet, die W\u00e4nde frisch Raufaser wei\u00df tapeziert.<\/p>\n<p>Sie betreten die Wohnung in einen kleinen Flurbereich, von dem K\u00fcche, Bad und Wohnzimmer aus begehbar sind, das Schlafzimmer ist nur durch das Wohnzimmer erreichbar.<\/p>\n<p>Die K\u00fcche mit allen Anschl\u00fcssen zum Einbau Ihrer eigenen Einbauk\u00fcche und es bleibt ggf. auch noch Platz f\u00fcr den kleinen Fr\u00fchst\u00fcckstisch.<\/p>\n<p>Das Bad, ein helles Tageslicht-Wannenbad.<\/p>\n<p>Wohn- und Schlafzimmer hintereinanderliegend und mit einer T\u00fcr verbunden. <\/p>\n<p>Einen Keller gibt es zu dieser Wohnung nicht.<\/p>\n<p>HInweis: Die Heizkosten sind in den Nebenkosten nicht inkludiert, da es sich hier um eine Gasetagenheizung handelt, die der Mieter, genau wie Strom, direkt mit dem Versorger seiner Wahl abrechnet.<\/p>\n<div class=\"block-title-wrap\">\n<h2>Position<\/h2>\n<\/div>\n<p>Berger Stra\u00dfe is one of Frankfurt&#039;s most popular shopping and entertainment streets. The house is in the immediate vicinity of the &quot;Bornheim Mitte&quot; subway station and therefore has optimal connections. <\/p>\n<p>Mitten im Leben von Bornheim w\u00e4re wohl die richtige Beschreibung der Lage mit viel Gastro- und Einkaufsangebot, also nicht die ruhige Wohnlage am Stadtrand.<\/p>\n<div class=\"block-title-wrap\">\n<h2>Miscellaneous<\/h2>\n<\/div>\n<p>Arrange your viewing appointment with our office, we look forward to your call today. <\/p>\n<p>Our fixed office hours are usually Monday to Friday between 9 a.m. and 5 p.m. At other times we are usually away on external appointments and therefore not always directly reachable.<\/p>\n<p>Note: Your request must contain a valid mobile phone number and an email address, otherwise it cannot be processed and will be deleted. <\/p>\n<p>Ideally, you would tell us the following in your email request:<br \/>\nHow many people are you looking for a new apartment for?<br \/>\nWhen are you looking for a new apartment?<br \/>\nDo you do something professionally?<br \/>\nThank you.<\/p>\n<p>Note: All information, including area information, comes from third parties (owners, managers, tenants) for whom we cannot accept any guarantee or liability. Errors and interim rentals remain reserved.<\/p>","protected":false},"excerpt":{"rendered":"<p>Objektbeschreibung In diesem zentral gelegenen Altbau aus der Jahrhundertwende direkt auf der Berger Stra\u00dfe wurde im 1. OG diese richtig gem\u00fctliche kleine 2-Zimmerwohnung grade fertig renoviert. Ideal f\u00fcr eine Single-Nutzung, max. jedoch 2 Personen und aufgrund des Grundrisses (hintereinander liegende Zimmer) f\u00fcr eine WG eher nicht m\u00f6glich. Ausstattung Der Boden jetzt neu mit schickem Vynil [&hellip;]<\/p>","protected":false},"author":2,"featured_media":69344,"parent":0,"menu_order":0,"template":"","property_type":[144],"property_status":[53,77],"property_feature":[],"property_label":[],"property_country":[56],"property_state":[],"property_city":[78],"property_area":[],"class_list":["post-60993","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-wohnung","property_status-referenzobjekte","property_status-vermietet","property_country-deutschland","property_city-frankfurt-main"],"property_meta":{"fave_currency":["EUR"],"fave_currency_info":["a:8:{s:2:\"id\";s:1:\"1\";s:13:\"currency_name\";s:4:\"Euro\";s:13:\"currency_code\";s:3:\"EUR\";s:15:\"currency_symbol\";s:3:\"\u20ac\";s:17:\"currency_position\";s:5:\"after\";s:16:\"currency_decimal\";s:1:\"0\";s:26:\"currency_decimal_separator\";s:1:\",\";s:27:\"currency_thousand_separator\";s:1:\".\";}"],"fave_property_price":["790"],"fave_property_sec_price":["890"],"fave_property_price_postfix":["(inkl. Nebenkosten)"],"fave_property_size":["38"],"fave_property_size_prefix":["qm"],"fave_property_land_postfix":["qm"],"fave_property_bedrooms":["2"],"fave_property_bathrooms":["1"],"fave_property_map":["1"],"fave_property_id":["142500620"],"fave_property_address":["Berger Stra\u00dfe"],"fave_property_zip":["60385"],"fave_property_country":["de_DE"],"fave_featured":["0"],"houzez_featured_listing_date":[""],"fave_agent_display_option":["agency_info"],"fave_prop_homeslider":["no"],"fave_additional_features_enable":["enable"],"fave_energy_class":["G"],"fave_epc_current_rating":["204.6 kWh\/(m\u00b2\u00b7a)"],"floor_plans":[null],"fave_multi_units":[null],"additional_features":["a:22:{i:0;a:2:{s:29:\"fave_additional_feature_title\";s:9:\"Objekt-ID\";s:29:\"fave_additional_feature_value\";s:9:\"142500620\";}i:1;a:2:{s:29:\"fave_additional_feature_title\";s:9:\"Objekttyp\";s:29:\"fave_additional_feature_value\";s:7:\"Wohnung\";}i:2;a:2:{s:29:\"fave_additional_feature_title\";s:7:\"Adresse\";s:29:\"fave_additional_feature_value\";s:20:\"60385 Frankfurt\/Main\";}i:3;a:2:{s:29:\"fave_additional_feature_title\";s:5:\"Etage\";s:29:\"fave_additional_feature_value\";s:1:\"1\";}i:4;a:2:{s:29:\"fave_additional_feature_title\";s:14:\"Etagen im Haus\";s:29:\"fave_additional_feature_value\";s:1:\"4\";}i:5;a:2:{s:29:\"fave_additional_feature_title\";s:15:\"Wohnfl\u00e4che ca.\";s:29:\"fave_additional_feature_value\";s:2:\"38\";}i:6;a:2:{s:29:\"fave_additional_feature_title\";s:6:\"Zimmer\";s:29:\"fave_additional_feature_value\";s:1:\"2\";}i:7;a:2:{s:29:\"fave_additional_feature_title\";s:9:\"Haustiere\";s:29:\"fave_additional_feature_value\";s:13:\"nicht erlaubt\";}i:8;a:1:{s:29:\"fave_additional_feature_title\";s:11:\"Heizungsart\";}i:9;a:2:{s:29:\"fave_additional_feature_title\";s:27:\"Wesentlicher Energietr\u00e4ger\";s:29:\"fave_additional_feature_value\";s:3:\"Gas\";}i:10;a:1:{s:29:\"fave_additional_feature_title\";s:7:\"Baujahr\";}i:11;a:2:{s:29:\"fave_additional_feature_title\";s:7:\"Zustand\";s:29:\"fave_additional_feature_value\";s:19:\"teil-\/vollrenoviert\";}i:12;a:2:{s:29:\"fave_additional_feature_title\";s:13:\"Verf\u00fcgbar ab\";s:29:\"fave_additional_feature_value\";s:20:\"sofort, 1.6.\/15.6.23\";}i:13;a:2:{s:29:\"fave_additional_feature_title\";s:7:\"Kaution\";s:29:\"fave_additional_feature_value\";s:20:\"3 Monatsmieten netto\";}i:14;a:2:{s:29:\"fave_additional_feature_title\";s:9:\"Kaltmiete\";s:29:\"fave_additional_feature_value\";s:3:\"790\";}i:15;a:2:{s:29:\"fave_additional_feature_title\";s:11:\"Nebenkosten\";s:29:\"fave_additional_feature_value\";s:3:\"100\";}i:16;a:2:{s:29:\"fave_additional_feature_title\";s:9:\"Warmmiete\";s:29:\"fave_additional_feature_value\";s:3:\"890\";}i:17;a:2:{s:29:\"fave_additional_feature_title\";s:17:\"Energieausweistyp\";s:29:\"fave_additional_feature_value\";s:9:\"VERBRAUCH\";}i:18;a:2:{s:29:\"fave_additional_feature_title\";s:17:\"Ausstellungsdatum\";s:29:\"fave_additional_feature_value\";s:4:\"2008\";}i:19;a:2:{s:29:\"fave_additional_feature_title\";s:21:\"Prim\u00e4renergietr\u00e4ger\";s:29:\"fave_additional_feature_value\";s:3:\"Gas\";}i:20;a:2:{s:29:\"fave_additional_feature_title\";s:13:\"Energiebedarf\";s:29:\"fave_additional_feature_value\";s:18:\"204.6 kWh\/(m\u00b2\u00b7a)\";}i:21;a:2:{s:29:\"fave_additional_feature_title\";s:22:\"Energieeffizienzklasse\";s:29:\"fave_additional_feature_value\";s:1:\"G\";}}"],"fave_agents":["8214"],"fave_property_agency":["8215"],"fave_property_map_address":["Heidestra\u00dfe 158, 60385 Frankfurt am Main, Germany"],"fave_property_location":["50.12763,8.70973"],"houzez_geolocation_lat":["50.12763"],"houzez_geolocation_long":["8.70973"],"Objekt-ID":["142500620"],"Objekttyp":["Wohnung"],"Adresse":["60385 Frankfurt\/Main"],"Etage":["1"],"Etagen im Haus":["4"],"Wohnfl\u00e4che ca.":["38"],"Zimmer":["2"],"Haustiere":["nicht erlaubt"],"Heizungsart":[""],"Wesentlicher Energietr\u00e4ger":["Gas"],"Baujahr":[""],"Zustand":["teil-\/vollrenoviert"],"Verf\u00fcgbar ab":["sofort, 1.6.\/15.6.23"],"Kaution":["3 Monatsmieten netto"],"Kaltmiete":["790"],"Nebenkosten":["100"],"Warmmiete":["890"],"Energieausweistyp":["VERBRAUCH"],"Ausstellungsdatum":["2008"],"Prim\u00e4renergietr\u00e4ger":["Gas"],"Energiebedarf":["204.6 kWh\/(m\u00b2\u00b7a)"],"Energieeffizienzklasse":[""],"Ausstattung \/ Merkmale":[""],"_wp_page_template":["default"],"fave_property_images":["69344","69345","69346","69347","69348","69349","69350","69351","69352","69353","69354"],"_thumbnail_id":["69344"],"houzez_total_property_views":["280"],"houzez_views_by_date":["a:61:{s:10:\"09-08-2025\";i:2;s:10:\"09-10-2025\";i:3;s:10:\"09-26-2025\";i:2;s:10:\"09-28-2025\";i:1;s:10:\"09-29-2025\";i:1;s:10:\"10-05-2025\";i:2;s:10:\"10-07-2025\";i:1;s:10:\"10-08-2025\";i:1;s:10:\"10-15-2025\";i:5;s:10:\"10-27-2025\";i:2;s:10:\"10-30-2025\";i:3;s:10:\"10-31-2025\";i:1;s:10:\"11-01-2025\";i:1;s:10:\"11-04-2025\";i:2;s:10:\"11-05-2025\";i:2;s:10:\"11-07-2025\";i:1;s:10:\"11-09-2025\";i:1;s:10:\"11-20-2025\";i:1;s:10:\"11-22-2025\";i:2;s:10:\"11-25-2025\";i:2;s:10:\"11-27-2025\";i:1;s:10:\"11-28-2025\";i:1;s:10:\"11-30-2025\";i:3;s:10:\"12-02-2025\";i:1;s:10:\"12-03-2025\";i:1;s:10:\"12-04-2025\";i:2;s:10:\"12-21-2025\";i:3;s:10:\"12-25-2025\";i:1;s:10:\"12-31-2025\";i:1;s:10:\"01-02-2026\";i:4;s:10:\"01-03-2026\";i:1;s:10:\"01-12-2026\";i:2;s:10:\"01-14-2026\";i:2;s:10:\"01-17-2026\";i:2;s:10:\"01-20-2026\";i:4;s:10:\"01-22-2026\";i:2;s:10:\"02-02-2026\";i:3;s:10:\"02-09-2026\";i:2;s:10:\"02-10-2026\";i:1;s:10:\"02-11-2026\";i:1;s:10:\"02-12-2026\";i:1;s:10:\"02-13-2026\";i:1;s:10:\"02-14-2026\";i:3;s:10:\"02-22-2026\";i:3;s:10:\"03-12-2026\";i:2;s:10:\"03-13-2026\";i:1;s:10:\"03-14-2026\";i:2;s:10:\"03-24-2026\";i:2;s:10:\"03-29-2026\";i:1;s:10:\"03-30-2026\";i:1;s:10:\"04-04-2026\";i:3;s:10:\"04-13-2026\";i:1;s:10:\"04-15-2026\";i:2;s:10:\"04-16-2026\";i:1;s:10:\"04-21-2026\";i:2;s:10:\"04-26-2026\";i:3;s:10:\"04-27-2026\";i:2;s:10:\"05-01-2026\";i:1;s:10:\"05-04-2026\";i:1;s:10:\"05-08-2026\";i:4;s:10:\"05-13-2026\";i:2;}"],"houzez_recently_viewed":["2026-05-13 03:34:18"],"_edit_lock":["1768056936:2"],"_elementor_page_assets":["a:0:{}"]},"_links":{"self":[{"href":"https:\/\/angebote.immobilienmoser.de\/en\/wp-json\/wp\/v2\/properties\/60993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/angebote.immobilienmoser.de\/en\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/angebote.immobilienmoser.de\/en\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/angebote.immobilienmoser.de\/en\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/angebote.immobilienmoser.de\/en\/wp-json\/wp\/v2\/properties\/60993\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/angebote.immobilienmoser.de\/en\/wp-json\/wp\/v2\/media\/69344"}],"wp:attachment":[{"href":"https:\/\/angebote.immobilienmoser.de\/en\/wp-json\/wp\/v2\/media?parent=60993"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/angebote.immobilienmoser.de\/en\/wp-json\/wp\/v2\/property_type?post=60993"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/angebote.immobilienmoser.de\/en\/wp-json\/wp\/v2\/property_status?post=60993"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/angebote.immobilienmoser.de\/en\/wp-json\/wp\/v2\/property_feature?post=60993"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/angebote.immobilienmoser.de\/en\/wp-json\/wp\/v2\/property_label?post=60993"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/angebote.immobilienmoser.de\/en\/wp-json\/wp\/v2\/property_country?post=60993"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/angebote.immobilienmoser.de\/en\/wp-json\/wp\/v2\/property_state?post=60993"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/angebote.immobilienmoser.de\/en\/wp-json\/wp\/v2\/property_city?post=60993"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/angebote.immobilienmoser.de\/en\/wp-json\/wp\/v2\/property_area?post=60993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}